{"id":8908,"date":"2018-03-30T09:00:58","date_gmt":"2018-03-30T09:00:58","guid":{"rendered":"https:\/\/endoscopiaterapeutica.net\/pt\/uncategorized\/quiz-lesao-plano-elevada-de-esofago\/"},"modified":"2022-06-17T14:46:41","modified_gmt":"2022-06-17T14:46:41","slug":"quiz-lesao-plano-elevada-de-esofago","status":"publish","type":"post","link":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/","title":{"rendered":"QUIZ! Les\u00e3o plano elevada de es\u00f4fago"},"content":{"rendered":"<p><a href=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2021\/09\/acantose-glicogenica3.jpg\" data-rel=\"penci-gallery-image-content\" ><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-8679\" src=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2021\/09\/acantose-glicogenica3.jpg\" alt=\"\" width=\"697\" height=\"577\"><\/a><\/p>\n<p>Paciente de 67 anos, tabagista, assintom\u00e1tico.&nbsp; Durante uma endoscopia de rotina&nbsp;foi identificada a les\u00e3o acima, localizada no es\u00f4fago m\u00e9dio. Para melhor investigar a les\u00e3o foi realizada cromoscopia com Lugol.<\/p>\n<p>Qual o prov\u00e1vel diagn\u00f3stico?<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Paciente de 67 anos, tabagista, assintom\u00e1tico.&nbsp; Durante uma endoscopia de rotina&nbsp;foi identificada a les\u00e3o&hellip;<\/p>\n","protected":false},"author":2464,"featured_media":8909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[143],"tags":[],"ano":[270],"tipo":[153],"volume":[263],"class_list":["post-8908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quiz","ano-270","tipo-endoscopia-digestiva-alta","volume-volume-i"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>QUIZ! Les\u00e3o plano elevada de es\u00f4fago &#8226; Endoscopia Terapeutica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QUIZ! Les\u00e3o plano elevada de es\u00f4fago\" \/>\n<meta property=\"og:description\" content=\"Paciente de 67 anos, tabagista, assintom\u00e1tico.&nbsp; Durante uma endoscopia de rotina&nbsp;foi identificada a les\u00e3o acima, localizada no es\u00f4fago m\u00e9dio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/\" \/>\n<meta property=\"og:site_name\" content=\"Endoscopia Terapeutica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/endoscopiaterapeutica\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-30T09:00:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-17T14:46:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2018\/03\/PictureIv.jpg?v=1632304951\" \/>\n\t<meta property=\"og:image:width\" content=\"324\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ivan R B Orso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivan R B Orso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/\"},\"author\":{\"name\":\"Ivan R B Orso\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#\\\/schema\\\/person\\\/96f14afeb86a76773da4cd09820010a1\"},\"headline\":\"QUIZ! Les\u00e3o plano elevada de es\u00f4fago\",\"datePublished\":\"2018-03-30T09:00:58+00:00\",\"dateModified\":\"2022-06-17T14:46:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/\"},\"wordCount\":52,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/PictureIv.jpg?v=1632304951\",\"articleSection\":[\"Quiz\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/\",\"url\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/\",\"name\":\"QUIZ! Les\u00e3o plano elevada de es\u00f4fago &#8226; Endoscopia Terapeutica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/PictureIv.jpg?v=1632304951\",\"datePublished\":\"2018-03-30T09:00:58+00:00\",\"dateModified\":\"2022-06-17T14:46:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/#primaryimage\",\"url\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/PictureIv.jpg?v=1632304951\",\"contentUrl\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/PictureIv.jpg?v=1632304951\",\"width\":324,\"height\":272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/quiz\\\/quiz-lesao-plano-elevada-de-esofago\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"QUIZ! Les\u00e3o plano elevada de es\u00f4fago\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/\",\"name\":\"Endoscopia Terapeutica\",\"description\":\"O Jornal Endoscopia Terap\u00eautica tem como objetivo compartilhar experi\u00eancias da pr\u00e1tica di\u00e1ria, al\u00e9m de prover atualiza\u00e7\u00f5es e discuss\u00f5es sobre endoscopia digestiva.\",\"publisher\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#organization\",\"name\":\"Endoscopia Terapeutica\",\"url\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/endter.jpg\",\"contentUrl\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/endter.jpg\",\"width\":720,\"height\":721,\"caption\":\"Endoscopia Terapeutica\"},\"image\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/endoscopiaterapeutica\",\"https:\\\/\\\/www.instagram.com\\\/endoscopy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@endoscopyonline\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#\\\/schema\\\/person\\\/96f14afeb86a76773da4cd09820010a1\",\"name\":\"Ivan R B Orso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Ivan-Orso-Site.jpg\",\"url\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Ivan-Orso-Site.jpg\",\"contentUrl\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Ivan-Orso-Site.jpg\",\"caption\":\"Ivan R B Orso\"},\"description\":\"Doutor em Ci\u00eancias em Gastroenterologia pela USP Especialista em Endoscopia Diagn\u00f3stica e Terap\u00eautica da Gastrocl\u00ednica Cascavel e do Hospital S\u00e3o Lucas FAG Coordenador da Resid\u00eancia M\u00e9dica em Cirurgia Geral e Professor de Gastroenterologia da Escola de Medicina da Faculdade Assis Gurgacz\",\"url\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/author\\\/ivan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"QUIZ! Les\u00e3o plano elevada de es\u00f4fago &#8226; Endoscopia Terapeutica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/","og_locale":"pt_BR","og_type":"article","og_title":"QUIZ! Les\u00e3o plano elevada de es\u00f4fago","og_description":"Paciente de 67 anos, tabagista, assintom\u00e1tico.&nbsp; Durante uma endoscopia de rotina&nbsp;foi identificada a les\u00e3o acima, localizada no es\u00f4fago m\u00e9dio.","og_url":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/","og_site_name":"Endoscopia Terapeutica","article_publisher":"https:\/\/www.facebook.com\/endoscopiaterapeutica","article_published_time":"2018-03-30T09:00:58+00:00","article_modified_time":"2022-06-17T14:46:41+00:00","og_image":[{"width":324,"height":272,"url":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2018\/03\/PictureIv.jpg?v=1632304951","type":"image\/jpeg"}],"author":"Ivan R B Orso","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ivan R B Orso","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/#article","isPartOf":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/"},"author":{"name":"Ivan R B Orso","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#\/schema\/person\/96f14afeb86a76773da4cd09820010a1"},"headline":"QUIZ! Les\u00e3o plano elevada de es\u00f4fago","datePublished":"2018-03-30T09:00:58+00:00","dateModified":"2022-06-17T14:46:41+00:00","mainEntityOfPage":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/"},"wordCount":52,"commentCount":3,"publisher":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#organization"},"image":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/#primaryimage"},"thumbnailUrl":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2018\/03\/PictureIv.jpg?v=1632304951","articleSection":["Quiz"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/","url":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/","name":"QUIZ! Les\u00e3o plano elevada de es\u00f4fago &#8226; Endoscopia Terapeutica","isPartOf":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/#primaryimage"},"image":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/#primaryimage"},"thumbnailUrl":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2018\/03\/PictureIv.jpg?v=1632304951","datePublished":"2018-03-30T09:00:58+00:00","dateModified":"2022-06-17T14:46:41+00:00","breadcrumb":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/#primaryimage","url":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2018\/03\/PictureIv.jpg?v=1632304951","contentUrl":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2018\/03\/PictureIv.jpg?v=1632304951","width":324,"height":272},{"@type":"BreadcrumbList","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-lesao-plano-elevada-de-esofago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/endoscopiaterapeutica.net\/pt\/"},{"@type":"ListItem","position":2,"name":"QUIZ! Les\u00e3o plano elevada de es\u00f4fago"}]},{"@type":"WebSite","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#website","url":"https:\/\/endoscopiaterapeutica.net\/pt\/","name":"Endoscopia Terapeutica","description":"O Jornal Endoscopia Terap\u00eautica tem como objetivo compartilhar experi\u00eancias da pr\u00e1tica di\u00e1ria, al\u00e9m de prover atualiza\u00e7\u00f5es e discuss\u00f5es sobre endoscopia digestiva.","publisher":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/endoscopiaterapeutica.net\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#organization","name":"Endoscopia Terapeutica","url":"https:\/\/endoscopiaterapeutica.net\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2023\/09\/endter.jpg","contentUrl":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2023\/09\/endter.jpg","width":720,"height":721,"caption":"Endoscopia Terapeutica"},"image":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/endoscopiaterapeutica","https:\/\/www.instagram.com\/endoscopy\/","https:\/\/www.youtube.com\/@endoscopyonline"]},{"@type":"Person","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#\/schema\/person\/96f14afeb86a76773da4cd09820010a1","name":"Ivan R B Orso","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2025\/04\/Ivan-Orso-Site.jpg","url":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2025\/04\/Ivan-Orso-Site.jpg","contentUrl":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2025\/04\/Ivan-Orso-Site.jpg","caption":"Ivan R B Orso"},"description":"Doutor em Ci\u00eancias em Gastroenterologia pela USP Especialista em Endoscopia Diagn\u00f3stica e Terap\u00eautica da Gastrocl\u00ednica Cascavel e do Hospital S\u00e3o Lucas FAG Coordenador da Resid\u00eancia M\u00e9dica em Cirurgia Geral e Professor de Gastroenterologia da Escola de Medicina da Faculdade Assis Gurgacz","url":"https:\/\/endoscopiaterapeutica.net\/pt\/author\/ivan\/"}]}},"_links":{"self":[{"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/posts\/8908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/users\/2464"}],"replies":[{"embeddable":true,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/comments?post=8908"}],"version-history":[{"count":2,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/posts\/8908\/revisions"}],"predecessor-version":[{"id":12162,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/posts\/8908\/revisions\/12162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/media\/8909"}],"wp:attachment":[{"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/media?parent=8908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/categories?post=8908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/tags?post=8908"},{"taxonomy":"ano","embeddable":true,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/ano?post=8908"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/tipo?post=8908"},{"taxonomy":"volume","embeddable":true,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/volume?post=8908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}