{"id":10920,"date":"2022-02-02T11:51:26","date_gmt":"2022-02-02T11:51:26","guid":{"rendered":"https:\/\/endoscopiaterapeutica.net\/pt\/?page_id=10920"},"modified":"2023-01-12T18:33:16","modified_gmt":"2023-01-12T18:33:16","slug":"ano-2022","status":"publish","type":"page","link":"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2022\/","title":{"rendered":"Ano 2022"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10920\" class=\"elementor elementor-10920\">\n\t\t\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-20 elementor-section elementor-top-section elementor-element elementor-element-c02c00c navegacao-ano elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c02c00c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-50 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bfc3948\" data-id=\"bfc3948\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba2f34f elementor-button-info elementor-align-left elementor-widget elementor-widget-button\" data-id=\"ba2f34f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2021\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\"><i class=\"penci-faicon fa fa-angle-double-left\"><\/i> 2021<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"penci-ercol-50 penci-ercol-order-2 penci-sticky-ct    elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-60c776b\" data-id=\"60c776b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c4833b elementor-button-info elementor-align-right elementor-widget elementor-widget-button\" data-id=\"0c4833b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2023\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">2023 <i class=\"penci-faicon fa fa-angle-double-right\"><\/i><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-d2942f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2942f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-320c86d\" data-id=\"320c86d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc0ba30 elementor-widget elementor-widget-penci-latest-posts\" data-id=\"fc0ba30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-latest-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <div id=\"pencilatest_posts_28987\" class=\"penci-latest-posts-sc penci-latest-posts-list penci-latest-posts-el penci-el-mixed-s1 penci-std-continue-center penci-std-excerpt-center penci-grid-excerpt-left\">\n\t\t\t\t\t\t\t\t\t\t\t                        <div class=\"penci-border-arrow penci-homepage-title penci-home-latest-posts style-5 pcalign-left pciconp-right pcicon-right\">\n                            <h3 class=\"inner-arrow\">\n                                <span>\n\t\t\t\t\t\t\t\t<span>\u00daltimos Artigos<\/span>                                <\/span>\n                            <\/h3>\n\t\t\t\t\t\t\t                        <\/div>\n\t\t\t\t\t                    <div class=\"penci-wrapper-posts-ajax\">\n\n                        <div class=\"penci-wrapper-posts-content pwid-default\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <ul data-layout=\"list\"\n                                    class=\"penci-wrapper-data penci-grid penci-shortcode-render\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"list-post penci-item-listp\">\n    <article id=\"post-14702\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/12\/PHOTO-2022-12-17-17-28-34-585x390.jpg?v=1671667564\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/estenose-biliar-indeterminada-importantes-conceitos-que-voce-precisa-conhecer\/\"\n                       title=\"Estenose biliar indeterminada \u2013 importantes conceitos que voc\u00ea precisa conhecer\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-151\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/assuntosgerais\/\"  rel=\"category tag\"><span style=\"\">Assuntos Gerais<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/estenose-biliar-indeterminada-importantes-conceitos-que-voce-precisa-conhecer\/\">Estenose biliar indeterminada \u2013 importantes conceitos que voc\u00ea precisa conhecer<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/gersonbrasil\/\">Gerson Brasil<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-12-27T06:30:00+00:00\">27\/12\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/gersonbrasil\/\">Gerson Brasil<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-12-27T06:30:00+00:00\">27\/12\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>A apresenta\u00e7\u00e3o cl\u00ednica das estenoses biliares \u00e9 ampla, variando de imagens incidentais e achados laboratoriais a sintomas de icter\u00edcia, dor abdominal, prurido e colangite, logo, uma hist\u00f3ria cl\u00ednica detalhada pode &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/estenose-biliar-indeterminada-importantes-conceitos-que-voce-precisa-conhecer\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-14668\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/12\/e020260f04-585x390.jpg?v=1671666993\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/assuntos-gerais-estenose-peptica-de-esofago\/\"\n                       title=\"Assuntos Gerais: Estenose P\u00e9ptica de Es\u00f4fago\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-151\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/assuntosgerais\/\"  rel=\"category tag\"><span style=\"\">Assuntos Gerais<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/assuntos-gerais-estenose-peptica-de-esofago\/\">Assuntos Gerais: Estenose P\u00e9ptica de Es\u00f4fago<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/guilherme\/\">Guilherme Sauniti<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-12-22T07:00:00+00:00\">22\/12\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/guilherme\/\">Guilherme Sauniti<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-12-22T07:00:00+00:00\">22\/12\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>As estenoses p\u00e9pticas s\u00e3o as estenoses benignas mais comuns do es\u00f4fago, por\u00e9m, seu diagn\u00f3stico tem diminu\u00eddo muito ao longo dos anos, principalmente devido ao uso dos inibidores de bomba de &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/assuntos-gerais-estenose-peptica-de-esofago\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-14637\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/12\/DICA-FIg-3.jpg?v=1671224164\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/diverticulose-do-colon-classificacao-dica-diverticular-inflammation-and-complication-assessment-porque-usar-na-rotina\/\"\n                       title=\"Diverticulose do c\u00f3lon &#8211; Classifica\u00e7\u00e3o DICA \u2013 \u201cDiverticular Inflammation and Complication Assessment\u201d \u2013 porque usar na rotina?\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-151\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/assuntosgerais\/\"  rel=\"category tag\"><span style=\"\">Assuntos Gerais<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/diverticulose-do-colon-classificacao-dica-diverticular-inflammation-and-complication-assessment-porque-usar-na-rotina\/\">Diverticulose do c\u00f3lon &#8211; Classifica\u00e7\u00e3o DICA \u2013 \u201cDiverticular Inflammation and Complication Assessment\u201d \u2013 porque usar na rotina?<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/bruno_medrado\/\">Bruno Medrado<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-12-16T20:57:48+00:00\">16\/12\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/bruno_medrado\/\">Bruno Medrado<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-12-16T20:57:48+00:00\">16\/12\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>A diverticulose do c\u00f3lon \u00e9 uma deformidade adquirida que pode afetar at\u00e9 cerca de 75% dos pacientes acima de 70 anos, sendo que at\u00e9 20% desses podem apresentar-se de forma &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/diverticulose-do-colon-classificacao-dica-diverticular-inflammation-and-complication-assessment-porque-usar-na-rotina\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-14280\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/12\/e019840f03-585x390.jpg?v=1669942034\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-estenose-de-esofago\/\"\n                       title=\"QUIZ !! Estenose de es\u00f4fago.\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-143\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/quiz\/\"  rel=\"category tag\"><span style=\"\">Quiz<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-estenose-de-esofago\/\">QUIZ !! Estenose de es\u00f4fago.<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/guilherme\/\">Guilherme Sauniti<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-12-02T07:00:00+00:00\">02\/12\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/guilherme\/\">Guilherme Sauniti<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-12-02T07:00:00+00:00\">02\/12\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>Paciente com 72 anos, com quadro cr\u00f4nico de pirose e queima\u00e7\u00e3o retroesternal, com tratamento irregular ao longo dos anos. Relata disfagia para s\u00f3lidos, e perda de peso n\u00e3o medida recentemente. &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-estenose-de-esofago\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-14177\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/11\/impn2-585x390.jpg?v=1669555255\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/criterios-de-fukuoka-para-ipmn\/\"\n                       title=\"Crit\u00e9rios de Fukuoka para IPMN\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-151\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/assuntosgerais\/\"  rel=\"category tag\"><span style=\"\">Assuntos Gerais<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/criterios-de-fukuoka-para-ipmn\/\">Crit\u00e9rios de Fukuoka para IPMN<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/bruno\/\">Bruno Martins<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-11-29T06:00:15+00:00\">29\/11\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/bruno\/\">Bruno Martins<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-11-29T06:00:15+00:00\">29\/11\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>O consenso de Fukuoka, tamb\u00e9m conhecido como crit\u00e9rios de Fukuoka ou guideline de Fukuoka, fornece as diretrizes para diagn\u00f3stico, seguimento e tratamento da neoplasia mucinosa papilar intraductal (IPMN) do p\u00e2ncreas. &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/criterios-de-fukuoka-para-ipmn\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-14166\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/11\/ERCP-585x390.jpeg?v=1669293896\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/artigoscomentados\/qual-melhor-forma-de-sedar-o-paciente-para-cpre-anestesia-geral-ou-sedacao-profunda-sem-intubacao\/\"\n                       title=\"Qual melhor forma de sedar o paciente para CPRE: anestesia geral ou seda\u00e7\u00e3o profunda sem intuba\u00e7\u00e3o?\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-142\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/artigoscomentados\/\"  rel=\"category tag\"><span style=\"\">Artigos Comentados<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/artigoscomentados\/qual-melhor-forma-de-sedar-o-paciente-para-cpre-anestesia-geral-ou-sedacao-profunda-sem-intubacao\/\">Qual melhor forma de sedar o paciente para CPRE: anestesia geral ou seda\u00e7\u00e3o profunda sem intuba\u00e7\u00e3o?<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/liviaarraes\/\">Livia Arraes<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-11-25T07:00:07+00:00\">25\/11\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/liviaarraes\/\">Livia Arraes<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-11-25T07:00:07+00:00\">25\/11\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>Os eventos adversos mais comuns na CPRE est\u00e3o relacionados a seda\u00e7\u00e3o. O tipo de seda\u00e7\u00e3o utilizado nas CPREs varia ao redor do mundo e inclui desde seda\u00e7\u00e3o realizada pelo pr\u00f3prio &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/artigoscomentados\/qual-melhor-forma-de-sedar-o-paciente-para-cpre-anestesia-geral-ou-sedacao-profunda-sem-intubacao\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-14111\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/11\/Maria-Sylvia-585x390.jpg?v=1669063501\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/voce-conhece-as-principais-contraindicacoes-a-confeccao-da-gastrostomia-endoscopica\/\"\n                       title=\"Voc\u00ea conhece as principais contraindica\u00e7\u00f5es \u00e0 confec\u00e7\u00e3o da gastrostomia endosc\u00f3pica?\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-151\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/assuntosgerais\/\"  rel=\"category tag\"><span style=\"\">Assuntos Gerais<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/voce-conhece-as-principais-contraindicacoes-a-confeccao-da-gastrostomia-endoscopica\/\">Voc\u00ea conhece as principais contraindica\u00e7\u00f5es \u00e0 confec\u00e7\u00e3o da gastrostomia endosc\u00f3pica?<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/msiribeiro\/\">Maria Sylvia Ierardi Ribeiro<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-11-22T07:00:05+00:00\">22\/11\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/msiribeiro\/\">Maria Sylvia Ierardi Ribeiro<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-11-22T07:00:05+00:00\">22\/11\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>O acesso enteral \u00e9 a cria\u00e7\u00e3o de uma via artificial atrav\u00e9s de um tubo apropriado para fornecer nutri\u00e7\u00e3o, medica\u00e7\u00f5es espec\u00edficas ou at\u00e9 mesmo realizar descompress\u00e3o. Essa comunica\u00e7\u00e3o com o trato &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/voce-conhece-as-principais-contraindicacoes-a-confeccao-da-gastrostomia-endoscopica\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-14012\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/11\/ESOFAGO-DISTAL-12071876-edit-585x390.jpg?v=1668092973\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-esofago-de-barrett\/\"\n                       title=\"Quiz! ES\u00d4FAGO DE BARRETT\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-143\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/quiz\/\"  rel=\"category tag\"><span style=\"\">Quiz<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-esofago-de-barrett\/\">Quiz! ES\u00d4FAGO DE BARRETT<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/rodrigo-rodrigues\/\">Rodrigo Rodrigues<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-11-11T14:17:51+00:00\">11\/11\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/rodrigo-rodrigues\/\">Rodrigo Rodrigues<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-11-11T14:17:51+00:00\">11\/11\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>Paciente do sexo masculino, 42 anos, obeso, tabagista, com sintomas de DRGE apresenta a seguinte imagem em sua primeira endoscopia alta.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/quiz\/quiz-esofago-de-barrett\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-13957\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/11\/image.png\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/voce-sabe-configurar-seu-bisturi-eletrico\/\"\n                       title=\"Voc\u00ea sabe configurar seu bisturi el\u00e9trico?\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-151\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/assuntosgerais\/\"  rel=\"category tag\"><span style=\"\">Assuntos Gerais<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/voce-sabe-configurar-seu-bisturi-eletrico\/\">Voc\u00ea sabe configurar seu bisturi el\u00e9trico?<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/jfoliveira\/\">Joel Fernandez de Oliveira<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-11-08T08:00:00+00:00\">08\/11\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/jfoliveira\/\">Joel Fernandez de Oliveira<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-11-08T08:00:00+00:00\">08\/11\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>O bisturi el\u00e9trico utiliza de corrente el\u00e9trica de alta frequ\u00eancia num tecido biol\u00f3gico, com intuito de conseguir efeitos m\u00e9dicos pela libera\u00e7\u00e3o de calor local. Os efeitos mais importantes para cirurgia &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/voce-sabe-configurar-seu-bisturi-eletrico\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-13940\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/11\/esge-585x390.png\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/artigoscomentados\/guideline-esge-sangramento-varicoso\/\"\n                       title=\"Guideline ESGE &#8211; Sangramento Varicoso\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-142\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/artigoscomentados\/\"  rel=\"category tag\"><span style=\"\">Artigos Comentados<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/artigoscomentados\/guideline-esge-sangramento-varicoso\/\">Guideline ESGE &#8211; Sangramento Varicoso<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/bruno\/\">Bruno Martins<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-11-04T06:19:00+00:00\">04\/11\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/bruno\/\">Bruno Martins<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-11-04T06:19:00+00:00\">04\/11\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>Em novembro 2022 a ESGE lan\u00e7ou seu novo guideline sobre sangramento varicoso. Esse guideline j\u00e1 incorpora os novos conceitos introduzidos pelo consenso de Baveno VII. O artigo na \u00edntegra pode &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/artigoscomentados\/guideline-esge-sangramento-varicoso\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-13931\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2015\/09\/esofcaustica1-585x390.jpg?v=1628560177\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/ingestao-de-causticos-e-endoscopia-quando-podemos-realmente-ajudar-no-quadro-agudo\/\"\n                       title=\"Ingest\u00e3o de c\u00e1usticos e endoscopia \u2013 quando podemos realmente ajudar no quadro agudo?\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-151\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/assuntosgerais\/\"  rel=\"category tag\"><span style=\"\">Assuntos Gerais<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/ingestao-de-causticos-e-endoscopia-quando-podemos-realmente-ajudar-no-quadro-agudo\/\">Ingest\u00e3o de c\u00e1usticos e endoscopia \u2013 quando podemos realmente ajudar no quadro agudo?<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/flavioferreira\/\">Fl\u00e1vio Ferreira<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-11-01T06:30:00+00:00\">01\/11\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/flavioferreira\/\">Fl\u00e1vio Ferreira<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-11-01T06:30:00+00:00\">01\/11\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>A ingest\u00e3o de c\u00e1usticos representa problema relevante tanto pelos danos agudos como cr\u00f4nicos, envolvendo pacientes de todas as faixas et\u00e1rias. Na popula\u00e7\u00e3o pedi\u00e1trica est\u00e1 habitualmente associada a ingest\u00e3o acidental principalmente &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/ingestao-de-causticos-e-endoscopia-quando-podemos-realmente-ajudar-no-quadro-agudo\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-13874\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/10\/image-7-546x390.png\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/achados-endoscopicos-relacionados-a-infeccao-pelo-h-pylori\/\"\n                       title=\"ACHADOS ENDOSC\u00d3PICOS RELACIONADOS \u00c0 INFEC\u00c7\u00c3O PELO H. PYLORI\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-151\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/assuntosgerais\/\"  rel=\"category tag\"><span style=\"\">Assuntos Gerais<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/achados-endoscopicos-relacionados-a-infeccao-pelo-h-pylori\/\">ACHADOS ENDOSC\u00d3PICOS RELACIONADOS \u00c0 INFEC\u00c7\u00c3O PELO H. PYLORI<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/nobre-renata\/?mab_v3=13874\">Renata Nobre&nbsp;e&nbsp;ELISA RYOKA BABA<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-10-21T08:00:00+00:00\">21\/10\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/nobre-renata\/?mab_v3=13874\">Renata Nobre&nbsp;e&nbsp;ELISA RYOKA BABA<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-10-21T08:00:00+00:00\">21\/10\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>O H pylori O Helicobacter pylori \u00e9 uma bact\u00e9ria gram-negativa que induz rea\u00e7\u00f5es celulares e qu\u00edmicas no est\u00f4mago, sendo considerada carcin\u00f3geno humano. Seu diagn\u00f3stico e tratamento t\u00eam importante papel na &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/achados-endoscopicos-relacionados-a-infeccao-pelo-h-pylori\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-13092\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/10\/esofagite-eosinofilica-585x390.png\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/atualizacoes-nos-criterios-diagnostico-da-esofagite-eosinofilica-eeo-parte-1\/\"\n                       title=\"Atualiza\u00e7\u00f5es nos Crit\u00e9rios Diagn\u00f3sticos da  Esofagite Eosinof\u00edlica (EEo)\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-151\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/assuntosgerais\/\"  rel=\"category tag\"><span style=\"\">Assuntos Gerais<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/atualizacoes-nos-criterios-diagnostico-da-esofagite-eosinofilica-eeo-parte-1\/\">Atualiza\u00e7\u00f5es nos Crit\u00e9rios Diagn\u00f3sticos da  Esofagite Eosinof\u00edlica (EEo)<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/gersonbrasil\/\">Gerson Brasil<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-10-18T06:31:00+00:00\">18\/10\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/gersonbrasil\/\">Gerson Brasil<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-10-18T06:31:00+00:00\">18\/10\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>CASO CL\u00cdNICO Homem, 30 anos, previamente h\u00edgido e sem comorbidades, foi submetido \u00e0 Endoscopia Digestiva Alta como proped\u00eautica de leve disfagia recorrente, principalmente com alguns alimentos, al\u00e9m de epis\u00f3dios espor\u00e1dicos &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/atualizacoes-nos-criterios-diagnostico-da-esofagite-eosinofilica-eeo-parte-1\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-13816\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/10\/image-2.png\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/dica-rapida-e-simples-que-salva-vidas-identifique-precocemente-o-carcinoma-de-celulas-escamosas-cec-no-esofago\/\"\n                       title=\"Dica R\u00e1pida e Simples que Salva Vidas: Identifique Precocemente o Carcinoma de C\u00e9lulas Escamosas (CEC) no Es\u00f4fago\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-151\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/assuntosgerais\/\"  rel=\"category tag\"><span style=\"\">Assuntos Gerais<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/dica-rapida-e-simples-que-salva-vidas-identifique-precocemente-o-carcinoma-de-celulas-escamosas-cec-no-esofago\/\">Dica R\u00e1pida e Simples que Salva Vidas: Identifique Precocemente o Carcinoma de C\u00e9lulas Escamosas (CEC) no Es\u00f4fago<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/jppontual\/\">Jo\u00e3o Paulo Pontual<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-10-15T00:03:39+00:00\">15\/10\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/jppontual\/\">Jo\u00e3o Paulo Pontual<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-10-15T00:03:39+00:00\">15\/10\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>Os endoscopistas ocidentais falham em diagnosticar 12% das neoplasias do trado digestivo superior.(1) Isso tamb\u00e9m te procupa? Saber que falhamos em diagnosticar uma fatia significativa de doen\u00e7as letais deixa qualquer &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/dica-rapida-e-simples-que-salva-vidas-identifique-precocemente-o-carcinoma-de-celulas-escamosas-cec-no-esofago\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n<li class=\"list-post penci-item-listp\">\n    <article id=\"post-13797\" class=\"item hentry\">\n\t\t            <div class=\"thumbnail\">\n\t\t\t\t\n\t\t\t\t                    <a class=\"penci-image-holder penci-lazy\"                       data-bgset=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2022\/10\/coledocolitiase-585x390.png\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/voce-sabe-a-melhor-forma-de-identificar-e-manejar-os-pacientes-com-risco-aumentado-de-coledocolitiase\/\"\n                       title=\"Voc\u00ea sabe a melhor forma de identificar e manejar os pacientes com risco aumentado de coledocolit\u00edase?\">\n                    <\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\n        <div class=\"content-list-right content-list-center\">\n            <div class=\"header-list-style\">\n\t\t\t\t                    <span class=\"cat\"><a style=\"\" class=\"penci-cat-name penci-cat-151\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/category\/assuntosgerais\/\"  rel=\"category tag\"><span style=\"\">Assuntos Gerais<\/span><\/a><\/span>\n\t\t\t\t\n                <h2 class=\"penci-entry-title entry-title grid-title penci_grid_title_df\"><a\n                            href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/voce-sabe-a-melhor-forma-de-identificar-e-manejar-os-pacientes-com-risco-aumentado-de-coledocolitiase\/\">Voc\u00ea sabe a melhor forma de identificar e manejar os pacientes com risco aumentado de coledocolit\u00edase?<\/a>\n                <\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"penci-hide-tagupdated\">\n\t\t\t<span class=\"author-italic author vcard\">por \t\t\t\t\t\t\t\t\t\t<a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/ivan\/\">Ivan R B Orso<\/a>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<time class=\"entry-date published\" datetime=\"2022-10-11T07:00:00+00:00\">11\/10\/2022<\/time>\t\t<\/div>\n\t\t\t\t\t\t\t                    <div class=\"grid-post-box-meta\">\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date-author author-italic author vcard\">por                                     <a class=\"author-url url fn n\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/author\/ivan\/\">Ivan R B Orso<\/a>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t                            <span class=\"otherl-date\"><time class=\"entry-date published\" datetime=\"2022-10-11T07:00:00+00:00\">11\/10\/2022<\/time><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n\n\t\t\t                <div class=\"item-content entry-content\">\n\t\t\t\t\t<p>A incid\u00eancia de colelit\u00edase sintom\u00e1tica entre os americanos adultos \u00e9 em torno de 10%. No Brasil &nbsp;estudos retrospectivos mostram uma incid\u00eancia de at\u00e9 9,3%.&nbsp;&nbsp; Entre estes pacientes, 10-20% podem apresentar &#8230;<\/p>\n                <\/div>\n\t\t\t\n\t\t\t                <div class=\"penci-readmore-btn penci-btn-align-left\">\n                    <a class=\"penci-btn-readmore\"\n                       href=\"https:\/\/endoscopiaterapeutica.net\/pt\/assuntosgerais\/voce-sabe-a-melhor-forma-de-identificar-e-manejar-os-pacientes-com-risco-aumentado-de-coledocolitiase\/\">Leia mais<i class=\"penci-faicon fa fa-angle-double-right\" ><\/i><\/a>\n                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n\n    <\/article>\n<\/li>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"penci-pagination align-left\"><ul class='page-numbers'>\n\t<li><span aria-current=\"page\" class=\"page-numbers current\">1<\/span><\/li>\n\t<li><a class=\"page-numbers\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/pages\/10920\/page\/2\/\">2<\/a><\/li>\n\t<li><a class=\"page-numbers\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/pages\/10920\/page\/3\/\">3<\/a><\/li>\n\t<li><span class=\"page-numbers dots\">&hellip;<\/span><\/li>\n\t<li><a class=\"page-numbers\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/pages\/10920\/page\/5\/\">5<\/a><\/li>\n\t<li><a class=\"next page-numbers\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/pages\/10920\/page\/2\/\"><i class=\"penci-faicon fa fa-angle-right\" ><\/i><\/a><\/li>\n<\/ul>\n<\/div>\t\t\t\t\t\t\t                        <\/div>\n\n\t\t\t\t\t\t                    <\/div>\n                <\/div>\n\t\t\t            <style>\n                                                                                                                                                                            <\/style>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>2021 2023 \u00daltimos Artigos Assuntos Gerais Estenose biliar indeterminada \u2013 importantes conceitos que voc\u00ea&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2067,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"class_list":["post-10920","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ano 2022 &#8226; Endoscopia Terapeutica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2022\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ano 2022\" \/>\n<meta property=\"og:description\" content=\"2021 2023 \u00daltimos Artigos Assuntos Gerais Estenose biliar indeterminada \u2013 importantes conceitos que voc\u00ea precisa conhecer por Gerson Brasil 27\/12\/2022 por\" \/>\n<meta property=\"og:url\" content=\"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Endoscopia Terapeutica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/endoscopiaterapeutica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-12T18:33:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/edicoes\\\/ano-2022\\\/\",\"url\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/edicoes\\\/ano-2022\\\/\",\"name\":\"Ano 2022 &#8226; Endoscopia Terapeutica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#website\"},\"datePublished\":\"2022-02-02T11:51:26+00:00\",\"dateModified\":\"2023-01-12T18:33:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/edicoes\\\/ano-2022\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/edicoes\\\/ano-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/edicoes\\\/ano-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edi\u00e7\u00f5es\",\"item\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/edicoes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ano 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/\",\"name\":\"Endoscopia Terapeutica\",\"description\":\"O Jornal Endoscopia Terap\u00eautica tem como objetivo compartilhar experi\u00eancias da pr\u00e1tica di\u00e1ria, al\u00e9m de prover atualiza\u00e7\u00f5es e discuss\u00f5es sobre endoscopia digestiva.\",\"publisher\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#organization\",\"name\":\"Endoscopia Terapeutica\",\"url\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/endter.jpg\",\"contentUrl\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/endter.jpg\",\"width\":720,\"height\":721,\"caption\":\"Endoscopia Terapeutica\"},\"image\":{\"@id\":\"https:\\\/\\\/endoscopiaterapeutica.net\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/endoscopiaterapeutica\",\"https:\\\/\\\/www.instagram.com\\\/endoscopy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@endoscopyonline\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ano 2022 &#8226; Endoscopia Terapeutica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2022\/","og_locale":"pt_BR","og_type":"article","og_title":"Ano 2022","og_description":"2021 2023 \u00daltimos Artigos Assuntos Gerais Estenose biliar indeterminada \u2013 importantes conceitos que voc\u00ea precisa conhecer por Gerson Brasil 27\/12\/2022 por","og_url":"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2022\/","og_site_name":"Endoscopia Terapeutica","article_publisher":"https:\/\/www.facebook.com\/endoscopiaterapeutica","article_modified_time":"2023-01-12T18:33:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2022\/","url":"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2022\/","name":"Ano 2022 &#8226; Endoscopia Terapeutica","isPartOf":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#website"},"datePublished":"2022-02-02T11:51:26+00:00","dateModified":"2023-01-12T18:33:16+00:00","breadcrumb":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2022\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/ano-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/endoscopiaterapeutica.net\/pt\/"},{"@type":"ListItem","position":2,"name":"Edi\u00e7\u00f5es","item":"https:\/\/endoscopiaterapeutica.net\/pt\/edicoes\/"},{"@type":"ListItem","position":3,"name":"Ano 2022"}]},{"@type":"WebSite","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#website","url":"https:\/\/endoscopiaterapeutica.net\/pt\/","name":"Endoscopia Terapeutica","description":"O Jornal Endoscopia Terap\u00eautica tem como objetivo compartilhar experi\u00eancias da pr\u00e1tica di\u00e1ria, al\u00e9m de prover atualiza\u00e7\u00f5es e discuss\u00f5es sobre endoscopia digestiva.","publisher":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/endoscopiaterapeutica.net\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#organization","name":"Endoscopia Terapeutica","url":"https:\/\/endoscopiaterapeutica.net\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2023\/09\/endter.jpg","contentUrl":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-content\/uploads\/2023\/09\/endter.jpg","width":720,"height":721,"caption":"Endoscopia Terapeutica"},"image":{"@id":"https:\/\/endoscopiaterapeutica.net\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/endoscopiaterapeutica","https:\/\/www.instagram.com\/endoscopy\/","https:\/\/www.youtube.com\/@endoscopyonline"]}]}},"_links":{"self":[{"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/pages\/10920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/comments?post=10920"}],"version-history":[{"count":7,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/pages\/10920\/revisions"}],"predecessor-version":[{"id":14910,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/pages\/10920\/revisions\/14910"}],"up":[{"embeddable":true,"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/pages\/2067"}],"wp:attachment":[{"href":"https:\/\/endoscopiaterapeutica.net\/pt\/wp-json\/wp\/v2\/media?parent=10920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}